{"id":244,"count":1,"description":"","link":"https:\/\/lilychen.net\/blog\/archives\/tag\/%e4%b8%ad%e6%b0%b8%e5%92%8c%e8%a6%aa%e5%ad%90%e6%a8%82%e5%9c%92","name":"\u4e2d\u6c38\u548c\u89aa\u5b50\u6a02\u5712","slug":"%e4%b8%ad%e6%b0%b8%e5%92%8c%e8%a6%aa%e5%ad%90%e6%a8%82%e5%9c%92","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/lilychen.net\/blog\/wp-json\/wp\/v2\/tags\/244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lilychen.net\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/lilychen.net\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/lilychen.net\/blog\/wp-json\/wp\/v2\/posts?tags=244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}